{"id":7221,"date":"2016-08-17T07:00:50","date_gmt":"2016-08-17T06:00:50","guid":{"rendered":"http:\/\/www.bbmag.co.uk\/pt-br\/?p=7221"},"modified":"2017-10-04T16:18:05","modified_gmt":"2017-10-04T15:18:05","slug":"rio-2016-musicas-brasileiras-sao-mais-procuradas-apos-abertura","status":"publish","type":"post","link":"https:\/\/www.bbmag.co.uk\/pt-br\/rio-2016-musicas-brasileiras-sao-mais-procuradas-apos-abertura\/","title":{"rendered":"Rio 2016 \u2013 M\u00fasicas brasileiras s\u00e3o mais procuradas ap\u00f3s a abertura"},"content":{"rendered":"<p>Ap\u00f3s a incr\u00edvel abertura dos Jogos Ol\u00edmpicos Rio 2016, as m\u00fasicas foram um dos destaques.<\/p>\n<p>Um momento que marcou o show foi o desfile da incr\u00edvel modelo Gisele B\u00fcndchen, que atravessou o Maracan\u00e3 mostrando a todos porque \u00e9 considerada a melhor modelo do mundo. Com muito charme e eleg\u00e2ncia, Gisele realizou sua passagem ao som de \u201cGarota de Ipanema\u201d, um dos cl\u00e1ssicos da M\u00fasica Popular Brasileira, que foi interpretada por Daniel Jobim, neto de Tom Jobim, que junto com Vin\u00edcius de Morais, comp\u00f4s essa bel\u00edssima can\u00e7\u00e3o.<\/p>\n<p>Ap\u00f3s o evento, a m\u00fasica teve um aumento estrondoso em sua procura, aumentando cerca de 1.200%, segundo o aplicativo de m\u00fasica Spotify.<\/p>\n<p>Outras m\u00fasicas brasileiras marcantes apresentadas na abertura foram \u201cPa\u00eds Tropical\u201d, \u201cAquele Abra\u00e7o\u201d, \u201cCanto de Ossanha\u201d e \u201cSand\u00e1lia de Prata\u201d, alguns dos \u201chinos\u201d da MPB.<\/p>\n<p>Listamos, abaixo, todas as m\u00fasicas da abertura, que n\u00f3s n\u00e3o cansamos de escutar!<\/p>\n<p>&#8211; \u201cAquele Abra\u00e7o\u201d, de Gilberto Gil \u2013 interpretado por Luiz Melodia<\/p>\n<p>&#8211; \u201cSamba de Ver\u00e3o\u201d, de Marcos Valle (instrumental)<\/p>\n<p>&#8211; \u00a0Hino Nacional brasileiro, interpretado por Paulinho da Viola<\/p>\n<p>&#8211; \u201cToada E Desafio\u201d, de Capiba (instrumental)<\/p>\n<p>&#8211; \u201cPindorama\u201d, composi\u00e7\u00e3o de Beto Villares, Ant\u00f4nio Alves Pinto, Renata Rosa e Marlui Miranda<\/p>\n<p>&#8211; \u201cGeometriza\u00e7\u00e3o\u201d, participa\u00e7\u00e3o de Fanta Konat\u00ea, Bukassa Kabengele, Sami e William Bordokan<\/p>\n<p>&#8211; \u201cConstru\u00e7\u00e3o\u201d, de Chico Buarque (instrumental)<\/p>\n<p>&#8211; \u201cSamba do Avi\u00e3o\u201d, de Tom Jobim (instrumental)<\/p>\n<p>&#8211; \u201cGarota de Ipanema\u201d, por Daniel Jobim ao piano<\/p>\n<p>&#8211; \u201cRap da Felicidade\u201d, Ludmilla<\/p>\n<p>&#8211; \u201cCanto de Ossanha\u201d, de Baden Powell e Vinicius de Moraes, interpretado por Elza Soares<\/p>\n<p>&#8211; Mash-up de \u201cDeixa a Vida me Levar\u201d, interpretado por Zeca Pagodinho e Marcelo D2<\/p>\n<p>&#8211;\u00a0 \u201cToquem os Tambores\u201d, interpretado por MC Soffia e Karol Conka<\/p>\n<p>&#8211; \u201cPop &#8211; As Disputas\u201d, composi\u00e7\u00e3o de Beto Villares e Ant\u00f4nio Alves Pinto<\/p>\n<p>&#8211; \u201cVelocidade do Eletro\u201d, Gang do Eletro<\/p>\n<p>&#8211; \u201cPa\u00eds Tropical\u201d, Jorge Ben<\/p>\n<p>&#8211; \u201cSand\u00e1lia de Prata\u201d, de Ary Barroso, interpretado por Caetano Veloso, Gilberto Gil e Anitta<\/p>\n<p>&#8211; 12 Baterias das escolas de samba do Rio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a incr\u00edvel abertura dos Jogos Ol\u00edmpicos Rio 2016, as m\u00fasicas foram um dos destaques. Um momento que marcou o show foi o desfile da incr\u00edvel modelo Gisele B\u00fcndchen, que atravessou o Maracan\u00e3 mostrando a todos porque \u00e9 considerada a melhor modelo do mundo. Com muito charme e eleg\u00e2ncia, Gisele realizou sua passagem ao som<\/p>\n<div class=\"read-more\"><a href=\"https:\/\/www.bbmag.co.uk\/pt-br\/rio-2016-musicas-brasileiras-sao-mais-procuradas-apos-abertura\/\" title=\"Saiba mais\">Saiba mais<\/a><\/div>\n","protected":false},"author":72,"featured_media":16461,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[67,76,74,88],"tags":[],"class_list":["post-7221","post","type-post","status-publish","format-standard","has-post-thumbnail","category-entretenimento","category-esportes","category-musica","category-turismo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.bbmag.co.uk\/wp-content\/uploads\/2016\/08\/abertura.jpg","jetpack-related-posts":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.bbmag.co.uk\/pt-br\/wp-json\/wp\/v2\/posts\/7221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bbmag.co.uk\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bbmag.co.uk\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bbmag.co.uk\/pt-br\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bbmag.co.uk\/pt-br\/wp-json\/wp\/v2\/comments?post=7221"}],"version-history":[{"count":0,"href":"https:\/\/www.bbmag.co.uk\/pt-br\/wp-json\/wp\/v2\/posts\/7221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bbmag.co.uk\/pt-br\/wp-json\/wp\/v2\/media\/16461"}],"wp:attachment":[{"href":"https:\/\/www.bbmag.co.uk\/pt-br\/wp-json\/wp\/v2\/media?parent=7221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bbmag.co.uk\/pt-br\/wp-json\/wp\/v2\/categories?post=7221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bbmag.co.uk\/pt-br\/wp-json\/wp\/v2\/tags?post=7221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}